{"id":1573,"date":"2018-09-10T14:02:28","date_gmt":"2018-09-10T12:02:28","guid":{"rendered":"http:\/\/www.montasio.com\/2018\/09\/10\/gli-appuntamenti-di-settembre-con-il-montasio-dop\/"},"modified":"2018-12-18T18:53:14","modified_gmt":"2018-12-18T17:53:14","slug":"montasio-dop-veranstaltungstermine-september","status":"publish","type":"post","link":"https:\/\/www.montasio.com\/de\/2018\/09\/10\/montasio-dop-veranstaltungstermine-september\/","title":{"rendered":"Montasio DOP Veranstaltungstermine September"},"content":{"rendered":"<p><strong>Ein Zwischenstopp in den wichtigsten italienischen St\u00e4dten, f\u00fcr das Kennenlernen der besten authentischen Delikatessen des Friauls, die mit der ital. gesch\u00fctzten Ursprungsbezeichnung DOP ausgezeichnet wurden.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Die vom Konsortium zum Schutz des DOP Montasio-K\u00e4ses geschaffene Wandertour mit Verkostungen und Aperitifs geht weiter. Das Ziel dabei ist das Kennenlernen der Qualit\u00e4t und Authentizit\u00e4t dieser Exzellenz auch au\u00dferhalb der regionalen Grenzen bekannt zu machen. Eine Tour, <strong>die andere St\u00e4dte in Norditalien besucht <\/strong><strong>und ihnen die Gelegenheit anbietet, den Montasio <\/strong><strong>begleitet <\/strong><strong>von edlen Weinen aus dem Friaul und Prosecco kennenzulernen. <\/strong><\/p>\n<p>\u201eEin hervorragendes Paar,\u201c &#8211; meint die Marketingleiterin Marina Cavedon &#8211; \u201edas in den letzten Monaten bereits viele Gaumen entz\u00fcckt hat\u201c. Ich m\u00f6chte Sie dabei auch an die markante Kombination aus frischem Montasio und dem superben stillen Wei\u00dfwein Ribolla Gialla ferma di Scarbolo, wie auch die spektakul\u00e4re Begleitung des Montasio Stravecchio, mit einer Reifung von mehr als 3 Jahren, durch den Zeitgenossen des Ribolla, dem Schioppettino aus dem gleichen Weingut Scarbolo Sergio di Cividale del Friuli aufmerksam machen.\u201c<\/p>\n<p>Dem Sinnengenuss ausgerichtete Verkostungen auch dank der technischen F\u00fchrung der nationalen Organisation der K\u00e4severkoster Onaf, welche beim Entdecken der D\u00fcfte und des Geschmacks, wie auch der olfaktorischen und taktilen Empfindungen dieses K\u00e4ses zur Verf\u00fcgung stehen.<\/p>\n<p>\u201eK\u00e4se ist ein mitrei\u00dfendes Agrarerzeugnis, welches einen analytischen, wie auch emotionalen Ansatz verdient\u201c meint\u00a0<strong>Maurizio Masotti, <\/strong>Pr\u00e4sident <strong>des Konsortiums. <\/strong><strong>Unser Ziel ist die F\u00f6rderung der Aufwertung von unserem hochwertigen K\u00e4se und das Verbreiten der Kenntnisse durch eingehende Verkostungen unserer Milchprodukte zu unterst\u00fctzen<\/strong>. Montasio wird von vielf\u00e4ltigen Geschm\u00e4cken und D\u00fcften gepr\u00e4gt, die durch die Art der verwendeten Milch, die Herstellung und Veredelung bestimmt und beeinflusst werden. Seine ern\u00e4hrungsphysiologischen Eigenschaften und Merkmale machen ihn zu einem vielseitig und zu jeder Tageszeit genie\u00dfbarem Produkt.\u201c<\/p>\n<p><strong>Die n\u00e4chsten Veranstaltungen <\/strong><\/p>\n<p>Am Donnerstag,\u00a0<strong> dem 14. September<\/strong>, wird in Siena, nach der Konferenz \u00fcber die Produktionskette von Korken von Carlos Dos Santos, dem Vorsitzenden aus Amorim, eine Verkostung von Montasio zusammen mit hervorragenden Wei\u00df- und Rotweinen aus Montecucco angeboten.<strong>\u00a0<\/strong><\/p>\n<p>Am Montag,<strong> dem 17. September<\/strong> wird im Laufe der Vorstellung des Buches \u201eDer universelle Winzer\u201c der Serie \u201eHandwerke der Kunst\u201c in der internationalen Kochschule <strong>Alma di Parma<\/strong> ein ganz besonderer Aperitif angeboten: Montasio-K\u00e4se begleitet vom hei\u00df geliebten Prosecco unter der Betreuung der Sommelier und Mitwirkenden f\u00fcr Identit\u00e0 Golose, Fr. Cinzia Benzi.<\/p>\n<p>Am <strong>20. September sollte man sich stattdessen nach Turin begeben<\/strong>, wo Montasio auf der Messe<strong> Salone del Gusto<\/strong> ausgestellt wird. Die Verkostungen begleiten die Besucher an allen f\u00fcnf Tagen der Messe bis zum 24. September.<\/p>\n<p>Am 29. und 30. September ist Montasio der Protagonist bei Caseus Veneti, der XIV Ausgabe des regionalen K\u00e4sewettbewerbs in Venetien, in der wundersch\u00f6nen Umgebung der <strong>Villa Contarini in <\/strong><strong>Piazzola Sul Brenta, der Provinz von Padua<\/strong>.\u00a0Ein Must f\u00fcr alle K\u00e4se-Fans, die bei dieser Gelegenheit einen professionellen Molkereifachmann kennenlernen, eine Pizza mit Montasio-K\u00e4se verkosten und sich von einem <strong> riesigen Frico <\/strong> bet\u00f6ren lassen k\u00f6nnen. Dieser soll f\u00fcr 1.200 Personen ausreichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Zwischenstopp in den wichtigsten italienischen St\u00e4dten, f\u00fcr das Kennenlernen der besten authentischen Delikatessen des Friauls, die mit der ital. gesch\u00fctzten Ursprungsbezeichnung DOP ausgezeichnet wurden. \u00a0 Die vom Konsortium zum Schutz des DOP Montasio-K\u00e4ses geschaffene Wandertour mit Verkostungen und Aperitifs geht weiter. Das Ziel dabei ist das Kennenlernen der Qualit\u00e4t und Authentizit\u00e4t dieser Exzellenz auch [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3754,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[113],"tags":[164,165,117,166,167,163],"acf":[],"_links":{"self":[{"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/posts\/1573"}],"collection":[{"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/comments?post=1573"}],"version-history":[{"count":0,"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/posts\/1573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/media\/3754"}],"wp:attachment":[{"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/media?parent=1573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/categories?post=1573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.montasio.com\/de\/wp-json\/wp\/v2\/tags?post=1573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}